{"id":148993,"date":"2026-03-10T11:34:14","date_gmt":"2026-03-10T10:34:14","guid":{"rendered":"https:\/\/megagrawww.com\/?post_type=product&#038;p=148993"},"modified":"2026-03-10T11:34:48","modified_gmt":"2026-03-10T10:34:48","slug":"collier-fanzone-19","status":"publish","type":"product","link":"https:\/\/megagrawww.com\/index.php\/produit\/collier-fanzone-19\/","title":{"rendered":"COLLIER FANZONE"},"content":{"rendered":"<p>Pendentif en m\u00e9tal mont\u00e9 d&#8217;un cam\u00e9e en c\u00e9ramique (4cm*3cm) imprim\u00e9e artisanalement par mes soins.<br \/>\nCollier chainette \u00e0 billes de 77cm (Vous avez la possibilit\u00e9 de le raccourcir en coupant des billes).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pendentif en m\u00e9tal mont\u00e9 d&#8217;un cam\u00e9e en c\u00e9ramique (4cm*3cm) imprim\u00e9e artisanalement par mes soins. Collier chainette \u00e0 billes de 77cm (Vous avez la possibilit\u00e9 de le raccourcir en coupant des billes).<\/p>\n","protected":false},"featured_media":148979,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[211,35,201,198,220,210],"product_tag":[],"class_list":{"0":"post-148993","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-art","7":"product_cat-colliers","8":"product_cat-fanzone","9":"product_cat-modele","10":"product_cat-style","11":"product_cat-tv","13":"first","14":"instock","15":"sold-individually","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>COLLIER FANZONE &ndash; MEGAGRAWWW<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/megagrawww.com\/index.php\/produit\/collier-fanzone-19\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COLLIER FANZONE &ndash; MEGAGRAWWW\" \/>\n<meta property=\"og:description\" content=\"Pendentif en m\u00e9tal mont\u00e9 d&#8217;un cam\u00e9e en c\u00e9ramique (4cm*3cm) imprim\u00e9e artisanalement par mes soins. Collier chainette \u00e0 billes de 77cm (Vous avez la possibilit\u00e9 de le raccourcir en coupant des billes).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/megagrawww.com\/index.php\/produit\/collier-fanzone-19\/\" \/>\n<meta property=\"og:site_name\" content=\"MEGAGRAWWW\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T10:34:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/megagrawww.com\/wp-content\/uploads\/2026\/03\/FanzoneIMG_6236.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"1 minute\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/megagrawww.com\/#\/schema\/person\/0278d8a82bfbea6605a2b97d8603bf52\",\"name\":\"Audrey Masson\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/megagrawww.com\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/927b85c0b45b84bb4d4f7b1b2f1afa94d0e9c29cc34c955a6784753d35cb8135?s=96&d=mm&r=g\",\"caption\":\"Audrey Masson\"},\"logo\":{\"@id\":\"https:\/\/megagrawww.com\/#personlogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/megagrawww.com\/#website\",\"url\":\"https:\/\/megagrawww.com\/\",\"name\":\"MEGAGRAWWW\",\"description\":\"Cr\\u00e9ation de bijoux en porcelaine\",\"publisher\":{\"@id\":\"https:\/\/megagrawww.com\/#\/schema\/person\/0278d8a82bfbea6605a2b97d8603bf52\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/megagrawww.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/megagrawww.com\/index.php\/produit\/collier-fanzone-19\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/megagrawww.com\/wp-content\/uploads\/2026\/03\/FanzoneIMG_6236.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/megagrawww.com\/index.php\/produit\/collier-fanzone-19\/#webpage\",\"url\":\"https:\/\/megagrawww.com\/index.php\/produit\/collier-fanzone-19\/\",\"name\":\"COLLIER FANZONE &ndash; MEGAGRAWWW\",\"isPartOf\":{\"@id\":\"https:\/\/megagrawww.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/megagrawww.com\/index.php\/produit\/collier-fanzone-19\/#primaryimage\"},\"datePublished\":\"2026-03-10T10:34:14+00:00\",\"dateModified\":\"2026-03-10T10:34:48+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/megagrawww.com\/index.php\/produit\/collier-fanzone-19\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/megagrawww.com\/index.php\/wp-json\/wp\/v2\/product\/148993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megagrawww.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/megagrawww.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megagrawww.com\/index.php\/wp-json\/wp\/v2\/media\/148979"}],"wp:attachment":[{"href":"https:\/\/megagrawww.com\/index.php\/wp-json\/wp\/v2\/media?parent=148993"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/megagrawww.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=148993"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/megagrawww.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=148993"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/megagrawww.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=148993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}